{"id":110744,"date":"2024-08-03T20:42:16","date_gmt":"2024-08-03T18:42:16","guid":{"rendered":"https:\/\/saldaarredamenti.com\/prodotto\/art-8543\/"},"modified":"2025-05-11T22:57:10","modified_gmt":"2025-05-11T20:57:10","slug":"art-8543","status":"publish","type":"product","link":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/","title":{"rendered":"Art. 8543"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Bed Louis XV, headboard and frame upholstered. Mod.BIS: headboard with fabric bord and nails finishing.<\/p>\n","protected":false},"featured_media":106338,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1446],"product_tag":[],"class_list":["post-110744","product","type-product","status-publish","has-post-thumbnail","product_cat-beds","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/prodotti\\\/#listItem\",\"name\":\"Prodotti\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/prodotti\\\/#listItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/saldaarredamenti.com\\\/prodotti\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/category\\\/beds\\\/#listItem\",\"name\":\"Beds\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/category\\\/beds\\\/#listItem\",\"position\":3,\"name\":\"Beds\",\"item\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/category\\\/beds\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#listItem\",\"name\":\"Art. 8543\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/prodotti\\\/#listItem\",\"name\":\"Prodotti\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#listItem\",\"position\":4,\"name\":\"Art. 8543\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/category\\\/beds\\\/#listItem\",\"name\":\"Beds\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#itempage\",\"url\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/\",\"name\":\"Art. 8543 | SALDA Arredamenti\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/saldaarredamenti.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SaldaArt8543.jpg\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#mainImage\",\"width\":1132,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#mainImage\"},\"datePublished\":\"2024-08-03T20:42:16+02:00\",\"dateModified\":\"2025-05-11T22:57:10+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/#organization\",\"name\":\"SALDA Arredamenti\",\"url\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/saldaarredamenti.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Logo_150x150.png\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#organizationLogo\",\"width\":150,\"height\":150},\"image\":{\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/products\\\/art-8543\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/\",\"name\":\"SALDA Arredamenti\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/saldaarredamenti.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Art. 8543 | SALDA Arredamenti","description":"","canonical_url":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/saldaarredamenti.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/prodotti\/#listItem","name":"Prodotti"}},{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/prodotti\/#listItem","position":2,"name":"Prodotti","item":"https:\/\/saldaarredamenti.com\/prodotti\/","nextItem":{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/category\/beds\/#listItem","name":"Beds"},"previousItem":{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/category\/beds\/#listItem","position":3,"name":"Beds","item":"https:\/\/saldaarredamenti.com\/en\/category\/beds\/","nextItem":{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#listItem","name":"Art. 8543"},"previousItem":{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/prodotti\/#listItem","name":"Prodotti"}},{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#listItem","position":4,"name":"Art. 8543","previousItem":{"@type":"ListItem","@id":"https:\/\/saldaarredamenti.com\/en\/category\/beds\/#listItem","name":"Beds"}}]},{"@type":"ItemPage","@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#itempage","url":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/","name":"Art. 8543 | SALDA Arredamenti","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/saldaarredamenti.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/saldaarredamenti.com\/wp-content\/uploads\/2024\/08\/SaldaArt8543.jpg","@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#mainImage","width":1132,"height":800},"primaryImageOfPage":{"@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#mainImage"},"datePublished":"2024-08-03T20:42:16+02:00","dateModified":"2025-05-11T22:57:10+02:00"},{"@type":"Organization","@id":"https:\/\/saldaarredamenti.com\/en\/#organization","name":"SALDA Arredamenti","url":"https:\/\/saldaarredamenti.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/saldaarredamenti.com\/wp-content\/uploads\/2017\/11\/Logo_150x150.png","@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#organizationLogo","width":150,"height":150},"image":{"@id":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/saldaarredamenti.com\/en\/#website","url":"https:\/\/saldaarredamenti.com\/en\/","name":"SALDA Arredamenti","inLanguage":"en-US","publisher":{"@id":"https:\/\/saldaarredamenti.com\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"110744","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-03 19:22:47","updated":"2025-06-10 02:19:50","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/saldaarredamenti.com\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/saldaarredamenti.com\/prodotti\/\" title=\"Prodotti\">Prodotti<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/saldaarredamenti.com\/en\/category\/beds\/\" title=\"Beds\">Beds<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArt. 8543\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/saldaarredamenti.com\/en\/"},{"label":"Prodotti","link":"https:\/\/saldaarredamenti.com\/prodotti\/"},{"label":"Beds","link":"https:\/\/saldaarredamenti.com\/en\/category\/beds\/"},{"label":"Art. 8543","link":"https:\/\/saldaarredamenti.com\/en\/products\/art-8543\/"}],"_links":{"self":[{"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product\/110744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product\/110744\/revisions"}],"predecessor-version":[{"id":110745,"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product\/110744\/revisions\/110745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/media\/106338"}],"wp:attachment":[{"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/media?parent=110744"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product_brand?post=110744"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product_cat?post=110744"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/saldaarredamenti.com\/en\/wp-json\/wp\/v2\/product_tag?post=110744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}